{"id":82193,"date":"2016-02-23T14:27:07","date_gmt":"2016-02-23T13:27:07","guid":{"rendered":"http:\/\/www.cinevox.be\/?p=82193"},"modified":"2016-07-19T10:32:44","modified_gmt":"2016-07-19T08:32:44","slug":"les-premiers-les-derniers-a-la-recherche-de-la-purete-originelle","status":"publish","type":"post","link":"https:\/\/welovecinema.be\/fr\/les-premiers-les-derniers-a-la-recherche-de-la-purete-originelle\/","title":{"rendered":"Les premiers, les derniers\u00a0: \u00e0 la recherche de la puret\u00e9 originelle"},"content":{"rendered":"<p>Au classement des personnalit\u00e9s pr\u00e9f\u00e9r\u00e9es des cin\u00e9philes cinevoxiens, <strong>Bouli Lanners <\/strong>tr\u00f4ne sans aucun doute tout en haut de la liste. Logique\u00a0! L\u2019homme est gentil, ouvert, humble, il a des convictions humanistes tr\u00e8s fortes, et surtout il est tr\u00e8s talentueux.<\/p>\n<p>Il poss\u00e8de en outre une double carte rare\u00a0: il est un des seuls par chez nous \u00e0 \u00eatre aussi bon r\u00e9alisateur que com\u00e9dien. C\u2019est aussi un sc\u00e9nariste tr\u00e8s personnel et un meneur d\u2019hommes qui sait f\u00e9d\u00e9rer les \u00e9nergies sur un tournage. Quelqu\u2019un qui donne envie de l\u2019\u00e9pauler.<br \/>\nD\u2019<em>Ultranova<\/em> aux <em>G\u00e9ants <\/em>en passant par <em>Eldorado<\/em>, Bouli Lanners a impos\u00e9 un style et des pr\u00e9occupations qui sont assez uniques dans notre cin\u00e9ma\u00a0: il aime parler de l\u2019homme et de la nature, de la petite place de l\u2019homme au c\u0153ur de m\u00e8re Nature, et ses films poss\u00e8dent syst\u00e9matiquement trois axes tr\u00e8s forts\u00a0: une image \u00e0 couper le souffle, un son plus soign\u00e9 que chez la plupart de ses cong\u00e9n\u00e8res, et des bandes originales oscillant g\u00e9n\u00e9ralement entre folk songs bucoliques et sonorit\u00e9s plus m\u00e9lancoliques.<\/p>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<p><a href=\"http:\/\/www.cinevox.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h50_58.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-82202\" src=\"http:\/\/www.cinevox.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h50_58-800x336.jpg\" alt=\"\" width=\"640\" height=\"268\" srcset=\"https:\/\/welovecinema.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h50_58-800x336.jpg 800w, https:\/\/welovecinema.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h50_58-480x201.jpg 480w, https:\/\/welovecinema.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h50_58.jpg 1261w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><br \/>\nLa premi\u00e8re participation du bouillant Li\u00e9geois aux Magritte (en 2012) s\u2019\u00e9tait sold\u00e9e par un triomphe des <em>G\u00e9ants <\/em>dans un contexte tr\u00e8s concurrentiel (on se rappelle du <em>mano a mano<\/em> qui l\u2019opposait au <em>Gamin au V\u00e9lo<\/em>), ce qui signifie \u00e9galement que le sympathique barbu a une grosse cote au sein de la profession.<br \/>\nTout cela pour dire que l\u2019attente autour de <em>Les Premiers, les derniers, <\/em>son quatri\u00e8me long m\u00e9trage est \u00e9norme.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.cinevox.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2624131.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-large wp-image-82194\" src=\"http:\/\/www.cinevox.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2624131-450x600.jpg\" alt=\"\" width=\"450\" height=\"600\" srcset=\"https:\/\/welovecinema.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2624131-450x600.jpg 450w, https:\/\/welovecinema.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2624131-202x270.jpg 202w, https:\/\/welovecinema.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2624131.jpg 1200w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/a>L\u2019affiche puis la bande-annonce r\u00e9v\u00e9l\u00e9es d\u00e9but d\u00e9cembre ont achev\u00e9 d\u2019attiser les envies. On y per\u00e7oit d\u00e9j\u00e0 une ambiance et un ton uniques, qui se rattachent \u00e0 l\u2019univers de Bouli tout en le renouvelant.<\/p>\n<p>L\u2019eau \u00e0 la bouche, nous avions donc, avant de d\u00e9couvrir le film en vision de presse, plus de deux mois avant sa sortie.<\/p>\n<p>Bonne nouvelle\u00a0: les deux teasers d\u00e9j\u00e0 r\u00e9v\u00e9l\u00e9s sont tr\u00e8s fid\u00e8les \u00e0 l\u2019esprit, mais aussi au climat du film, qui suit la qu\u00eate de quatre personnages, leur fuite en avant vers\u2026 la lumi\u00e8re.<\/p>\n<p>Car c\u2019est bien de cela qu\u2019il s\u2019agit ici\u00a0: les quatre (cinq m\u00eame, si on compte\u2026 J\u00e9sus) h\u00e9ros du film cherchent l\u2019humanit\u00e9 dans un univers qui en manque singuli\u00e8rement, l\u2019humanit\u00e9 qu\u2019ils ont en eux et que ce monde a, d\u2019une mani\u00e8re ou d\u2019une autre, \u00e9touff\u00e9e.<\/p>\n<p>Dans un d\u00e9cor post-apocalyptique (l\u2018\u00e9poque et le lieu ne sont pas clairement d\u00e9finis), ils vont entrer en contact avec la nature et renouer avec leurs plus profonds instincts, se r\u00e9v\u00e9ler enfin \u00e0 travers les yeux soudain bienveillants des autres.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.cinevox.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h46_51.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-82196 size-large\" src=\"http:\/\/www.cinevox.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h46_51-800x341.jpg\" alt=\"\" width=\"640\" height=\"272\" srcset=\"https:\/\/welovecinema.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h46_51-800x341.jpg 800w, https:\/\/welovecinema.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h46_51-480x204.jpg 480w, https:\/\/welovecinema.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h46_51.jpg 1254w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>On a d\u00e9j\u00e0 beaucoup parl\u00e9 du pitch du film, mais il n\u2019est naturellement pas inutile de le r\u00e9p\u00e9ter ici\u00a0:<\/p>\n<p>Dans une plaine infinie balay\u00e9e par le vent, Cochise (Albert Dupontel) et Gilou (Bouli), deux ins\u00e9parables chasseurs de prime, sont \u00e0 la recherche d\u2019un t\u00e9l\u00e9phone vol\u00e9 au contenu sensible.<\/p>\n<p>Leur chemin va croiser celui d\u2019Esther (Aurore Broutin) et Willy (David Murgia), un couple en cavale.<br \/>\nWilly poss\u00e8de le portable s\u00e9curis\u00e9, mais il n\u2019a pas conscience que celui-ci pr\u00e9sente beaucoup d\u2019int\u00e9r\u00eat pour certaines personnes.<\/p>\n<p>Il a aussi un revolver \u00e0 la ceinture.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.cinevox.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h57_10.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-82197\" src=\"http:\/\/www.cinevox.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h57_10-800x384.jpg\" alt=\"\" width=\"640\" height=\"307\" srcset=\"https:\/\/welovecinema.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h57_10-800x384.jpg 800w, https:\/\/welovecinema.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h57_10-480x230.jpg 480w, https:\/\/welovecinema.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h57_10.jpg 1066w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><br \/>\nWilly et Esther sont une entit\u00e9, des ins\u00e9parables, des amoureux comme on n\u2019en fait plus, incapables de vivre cinq minutes l\u2019un sans l\u2019autre. Ils souffrent \u00e9galement d&rsquo;un l\u00e9ger handicap mental et comme nous le confiait Bouli, ces deux r\u00f4les-l\u00e0 \u00e9taient particuli\u00e8rement difficiles \u00e0 jouer.<br \/>\nSi la jeune Aurore Broutin qu\u2019on ne connaissait pas s\u2019en sort avec brio, David Murgia propose ici une prestation \u2026 extra-terrestre. Dans la lign\u00e9e du r\u00f4le qu\u2019il tenait dans <em>Rundskop,<\/em> mais sur un autre mode et avec nettement plus de temps pour installer son personnage, David signe une interpr\u00e9tation qui restera dans les annales au cin\u00e9ma.<\/p>\n<p>&nbsp;<\/p>\n<p>Alors que des com\u00e9diens mythiques comme Dustin Hoffman (<em>Rain man<\/em>) ou Sean Penn (<em>Sam I\u2019m Sam<\/em>) portaient aussi leur retard mental sur le visage, David a essentiellement travaill\u00e9 sa posture et sa voix. Pour le reste il est d\u2019une beaut\u00e9 sid\u00e9rante, film\u00e9 comme jamais auparavant il ne l\u2019a \u00e9t\u00e9. Le contraste est saisissant.<\/p>\n<p>Bouli nous confiait r\u00e9cemment qu\u2019il lui trouvait une gr\u00e2ce digne des peintures de Caravage et on ne peut qu\u2019\u00eatre d\u2019accord avec cette remarque. Parfois longuement muet, soudain volubile, agit\u00e9, effray\u00e9, amoureux, David Murgia joue sur toute une gamme qui n\u2019est pas \u00e0 la port\u00e9e du premier venu. Sans ostentation, tout en subtilit\u00e9. Sa composition est sid\u00e9rante.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.cinevox.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h48_04.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-82199\" src=\"http:\/\/www.cinevox.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h48_04-800x334.jpg\" alt=\"\" width=\"640\" height=\"267\" srcset=\"https:\/\/welovecinema.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h48_04-800x334.jpg 800w, https:\/\/welovecinema.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h48_04-480x200.jpg 480w, https:\/\/welovecinema.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h48_04.jpg 1258w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Pas \u00e9tonnant d\u2019ailleurs qu\u2019il soit lors d\u2019une sc\u00e8ne d\u2019une simplicit\u00e9 pourtant totale \u00e0 l\u2019origine d\u2019un torrent d\u2019\u00e9motions qui submerge le spectateur, soudain incapable de se contr\u00f4ler (note personnelle, mais on en reparle d\u00e8s que vous avez vu le film).<\/p>\n<p>&nbsp;<\/p>\n<p>Dire que nous sommes heureux de voir enfin un de nos plus grands espoirs ainsi servi au cin\u00e9ma alors que jusqu\u2019ici ses meilleures performances (\u00e0 l\u2019exception de <em>Rundskop<\/em> donc et du plus naturaliste <em>La t\u00eate la premi\u00e8re<\/em>) avaient \u00e9t\u00e9 r\u00e9serv\u00e9es \u00e0 la sc\u00e8ne, est un euph\u00e9misme de dimension intergalactique.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.cinevox.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h48_37.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-82201\" src=\"http:\/\/www.cinevox.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h48_37-800x333.jpg\" alt=\"\" width=\"640\" height=\"266\" srcset=\"https:\/\/welovecinema.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h48_37-800x333.jpg 800w, https:\/\/welovecinema.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h48_37-480x200.jpg 480w, https:\/\/welovecinema.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h48_37.jpg 1256w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Le niveau d\u2019interpr\u00e9tation coll\u00e9giale dans ce film est \u00e9videmment tr\u00e8s haut. Ce n\u2019est pas une surprise quand on voit le casting.<\/p>\n<p>Outre Dupontel et Lanners, fid\u00e8les \u00e0 ce qu\u2019on attend d\u2019eux, on croise ici la douce Qu\u00e9b\u00e9coise Suzanne Cl\u00e9ment ou, l\u00e0, un duo de com\u00e9diens mythiques\u00a0compos\u00e9 de Michael Lonsdale et Max Von Sidow r\u00e9unis dans une sc\u00e8ne (un plan en particulier) qui fera date dans l\u2019histoire.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.cinevox.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h54_05.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-82200\" src=\"http:\/\/www.cinevox.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h54_05-800x332.jpg\" alt=\"\" width=\"640\" height=\"265\" srcset=\"https:\/\/welovecinema.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h54_05-800x332.jpg 800w, https:\/\/welovecinema.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h54_05-480x199.jpg 480w, https:\/\/welovecinema.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h54_05.jpg 1262w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Film d\u2019ambiance, lent et sombre, qui remonte progressivement vers la lumi\u00e8re, m\u00e9lancolique en diable, <em>Les Premiers les derniers<\/em> est aussi illumin\u00e9 par le travail de quelques collaborateurs exceptionnels de Bouli\u00a0: le fid\u00e8le Jean-Paul De Zaetijd nous offre une image d\u00e9satur\u00e9e, m\u00e9tallique, du plus bel effet, son \u00e9quipe son (Jean Minondo, Marc Bastien, Thomas Gauder) nous plonge au c\u0153ur de la nature comme jamais, son d\u00e9corateur de g\u00e9nie (Paul Rouschop) et sa costumi\u00e8re hors pair (\u00c9lise Ancion, compagne de Bouli dans la vie) ach\u00e8vent de cr\u00e9er l\u2019ambiance unique du film.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.cinevox.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h45_48.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-82195\" src=\"http:\/\/www.cinevox.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h45_48-800x335.jpg\" alt=\"\" width=\"640\" height=\"268\" srcset=\"https:\/\/welovecinema.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h45_48-800x335.jpg 800w, https:\/\/welovecinema.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h45_48-480x201.jpg 480w, https:\/\/welovecinema.be\/wp-content\/uploads\/sites\/2\/2015\/12\/2015-12-16_20h45_48.jpg 1260w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><br \/>\nComment ne pas \u00e9voquer non plus la bande originale exceptionnelle compos\u00e9e par Pascal Humbert\u00a0? Ce nom n\u2019est peut-\u00eatre pas tr\u00e8s connu du grand public, mais Humbert est \u00e0 la base de quelques groupes mythiques dans un univers folk aux intonations gothiques. Il fut ainsi le bassiste de Sixteen Horsepower, de Wovenhand et du duo Lilium. Il est \u00e9galement un des membres de Detroit avec Bertrand Cantat qui pousse ici quelques vocalises sur un morceau \u00e9th\u00e9r\u00e9 et marquant.<\/p>\n<p>On retrouve dans la premi\u00e8re partie du g\u00e9n\u00e9rique une chanson connue de Wovenhand avec la voix de son charismatique leader David Eugene Edwards et, pour conclure, un titre de Micah P. Hinson.<br \/>\nTout cela n\u2019\u00e9voquera pas grand-chose aux non-initi\u00e9s, mais si le style vous int\u00e9resse, cette bande originale constitue, en soi, un argument non n\u00e9gociable pour se ruer dans les salles quand le film sortira, le 27 f\u00e9vrier.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00c0 la fois intime et universel, tendu et lumineux, <em>Les Premiers les Derniers<\/em> se pose d\u00e9j\u00e0 comme un des chocs esth\u00e9tiques de 2016. Le film que Bouli voulait faire. Le film qu\u2019il a r\u00e9alis\u00e9.<\/p>\n<p>L\u2019homme peut \u00eatre serein, sa mission est accomplie.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>(si cet article vous parle, n&rsquo;h\u00e9sitez pas \u00e0 le liker ou\/et \u00e0 le partager sur Facebook. Ce sont les meilleures fa\u00e7ons d&rsquo;attirer l&rsquo;attention de vos amis sur ce qui vous touche et de partager notre enthousiasme. Merci\u00a0pour\u00a0votre\u00a0soutien)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au classement des personnalit\u00e9s pr\u00e9f\u00e9r\u00e9es des cin\u00e9philes cinevoxiens, Bouli Lanners tr\u00f4ne sans aucun doute tout en haut de la liste. Logique\u00a0! L\u2019homme est gentil, ouvert, humble, il a des convictions humanistes tr\u00e8s fortes, et surtout il est tr\u00e8s talentueux. Il poss\u00e8de en outre une double carte rare\u00a0: il est un des seuls par chez nous &hellip;<\/p>\n","protected":false},"author":7,"featured_media":82204,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-82193","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-a-l-affiche"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les premiers, les derniers\u00a0: \u00e0 la recherche de la puret\u00e9 originelle - We Love Cinema<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/welovecinema.be\/fr\/les-premiers-les-derniers-a-la-recherche-de-la-purete-originelle\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les premiers, les derniers\u00a0: \u00e0 la recherche de la puret\u00e9 originelle - We Love Cinema\" \/>\n<meta property=\"og:description\" content=\"Au classement des personnalit\u00e9s pr\u00e9f\u00e9r\u00e9es des cin\u00e9philes cinevoxiens, Bouli Lanners tr\u00f4ne sans aucun doute tout en haut de la liste. Logique\u00a0! L\u2019homme est gentil, ouvert, humble, il a des convictions humanistes tr\u00e8s fortes, et surtout il est tr\u00e8s talentueux. Il poss\u00e8de en outre une double carte rare\u00a0: il est un des seuls par chez nous &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/welovecinema.be\/fr\/les-premiers-les-derniers-a-la-recherche-de-la-purete-originelle\/\" \/>\n<meta property=\"og:site_name\" content=\"We Love Cinema\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/welovecinema.be\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-23T13:27:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-19T08:32:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/welovecinema.be\/wp-content\/uploads\/sites\/2\/2010\/12\/2015-12-16_20h47_51.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1268\" \/>\n\t<meta property=\"og:image:height\" content=\"529\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Philippe.Pierquin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Philippe.Pierquin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/welovecinema.be\/fr\/les-premiers-les-derniers-a-la-recherche-de-la-purete-originelle\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/welovecinema.be\/fr\/les-premiers-les-derniers-a-la-recherche-de-la-purete-originelle\/\"},\"author\":{\"name\":\"Philippe.Pierquin\",\"@id\":\"https:\/\/welovecinema.be\/nl\/#\/schema\/person\/4b9b1d857f0943453a38a7c2859ef756\"},\"headline\":\"Les premiers, les derniers\u00a0: \u00e0 la recherche de la puret\u00e9 originelle\",\"datePublished\":\"2016-02-23T13:27:07+00:00\",\"dateModified\":\"2016-07-19T08:32:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/welovecinema.be\/fr\/les-premiers-les-derniers-a-la-recherche-de-la-purete-originelle\/\"},\"wordCount\":1390,\"publisher\":{\"@id\":\"https:\/\/welovecinema.be\/nl\/#organization\"},\"articleSection\":[\"A l'affiche\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/welovecinema.be\/fr\/les-premiers-les-derniers-a-la-recherche-de-la-purete-originelle\/\",\"url\":\"https:\/\/welovecinema.be\/fr\/les-premiers-les-derniers-a-la-recherche-de-la-purete-originelle\/\",\"name\":\"Les premiers, les derniers\u00a0: \u00e0 la recherche de la puret\u00e9 originelle - We Love Cinema\",\"isPartOf\":{\"@id\":\"https:\/\/welovecinema.be\/nl\/#website\"},\"datePublished\":\"2016-02-23T13:27:07+00:00\",\"dateModified\":\"2016-07-19T08:32:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/welovecinema.be\/fr\/les-premiers-les-derniers-a-la-recherche-de-la-purete-originelle\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/welovecinema.be\/fr\/les-premiers-les-derniers-a-la-recherche-de-la-purete-originelle\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/welovecinema.be\/fr\/les-premiers-les-derniers-a-la-recherche-de-la-purete-originelle\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/welovecinema.be\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les premiers, les derniers\u00a0: \u00e0 la recherche de la puret\u00e9 originelle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/welovecinema.be\/nl\/#website\",\"url\":\"https:\/\/welovecinema.be\/nl\/\",\"name\":\"We Love Cinema\",\"description\":\"Toute l\u2019information du cin\u00e9ma en Belgique\",\"publisher\":{\"@id\":\"https:\/\/welovecinema.be\/nl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/welovecinema.be\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/welovecinema.be\/nl\/#organization\",\"name\":\"We Love Cinema\",\"url\":\"https:\/\/welovecinema.be\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/welovecinema.be\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/welovecinema.be\/wp-content\/uploads\/sites\/2\/2023\/03\/Logo-We-Love-Cinema305x128.jpg\",\"contentUrl\":\"https:\/\/welovecinema.be\/wp-content\/uploads\/sites\/2\/2023\/03\/Logo-We-Love-Cinema305x128.jpg\",\"width\":305,\"height\":128,\"caption\":\"We Love Cinema\"},\"image\":{\"@id\":\"https:\/\/welovecinema.be\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/welovecinema.be\",\"https:\/\/www.youtube.com\/channel\/UCX5LYGVhnKvYauW4Nta4HJA\",\"https:\/\/www.instagram.com\/welovecinema.be\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/welovecinema.be\/nl\/#\/schema\/person\/4b9b1d857f0943453a38a7c2859ef756\",\"name\":\"Philippe.Pierquin\",\"url\":\"https:\/\/welovecinema.be\/fr\/author\/philippe-pierquin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les premiers, les derniers\u00a0: \u00e0 la recherche de la puret\u00e9 originelle - We Love Cinema","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/welovecinema.be\/fr\/les-premiers-les-derniers-a-la-recherche-de-la-purete-originelle\/","og_locale":"fr_FR","og_type":"article","og_title":"Les premiers, les derniers\u00a0: \u00e0 la recherche de la puret\u00e9 originelle - We Love Cinema","og_description":"Au classement des personnalit\u00e9s pr\u00e9f\u00e9r\u00e9es des cin\u00e9philes cinevoxiens, Bouli Lanners tr\u00f4ne sans aucun doute tout en haut de la liste. Logique\u00a0! L\u2019homme est gentil, ouvert, humble, il a des convictions humanistes tr\u00e8s fortes, et surtout il est tr\u00e8s talentueux. Il poss\u00e8de en outre une double carte rare\u00a0: il est un des seuls par chez nous &hellip;","og_url":"https:\/\/welovecinema.be\/fr\/les-premiers-les-derniers-a-la-recherche-de-la-purete-originelle\/","og_site_name":"We Love Cinema","article_publisher":"https:\/\/www.facebook.com\/welovecinema.be","article_published_time":"2016-02-23T13:27:07+00:00","article_modified_time":"2016-07-19T08:32:44+00:00","og_image":[{"width":1268,"height":529,"url":"https:\/\/welovecinema.be\/wp-content\/uploads\/sites\/2\/2010\/12\/2015-12-16_20h47_51.jpg","type":"image\/jpeg"}],"author":"Philippe.Pierquin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Philippe.Pierquin","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/welovecinema.be\/fr\/les-premiers-les-derniers-a-la-recherche-de-la-purete-originelle\/#article","isPartOf":{"@id":"https:\/\/welovecinema.be\/fr\/les-premiers-les-derniers-a-la-recherche-de-la-purete-originelle\/"},"author":{"name":"Philippe.Pierquin","@id":"https:\/\/welovecinema.be\/nl\/#\/schema\/person\/4b9b1d857f0943453a38a7c2859ef756"},"headline":"Les premiers, les derniers\u00a0: \u00e0 la recherche de la puret\u00e9 originelle","datePublished":"2016-02-23T13:27:07+00:00","dateModified":"2016-07-19T08:32:44+00:00","mainEntityOfPage":{"@id":"https:\/\/welovecinema.be\/fr\/les-premiers-les-derniers-a-la-recherche-de-la-purete-originelle\/"},"wordCount":1390,"publisher":{"@id":"https:\/\/welovecinema.be\/nl\/#organization"},"articleSection":["A l'affiche"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/welovecinema.be\/fr\/les-premiers-les-derniers-a-la-recherche-de-la-purete-originelle\/","url":"https:\/\/welovecinema.be\/fr\/les-premiers-les-derniers-a-la-recherche-de-la-purete-originelle\/","name":"Les premiers, les derniers\u00a0: \u00e0 la recherche de la puret\u00e9 originelle - We Love Cinema","isPartOf":{"@id":"https:\/\/welovecinema.be\/nl\/#website"},"datePublished":"2016-02-23T13:27:07+00:00","dateModified":"2016-07-19T08:32:44+00:00","breadcrumb":{"@id":"https:\/\/welovecinema.be\/fr\/les-premiers-les-derniers-a-la-recherche-de-la-purete-originelle\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/welovecinema.be\/fr\/les-premiers-les-derniers-a-la-recherche-de-la-purete-originelle\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/welovecinema.be\/fr\/les-premiers-les-derniers-a-la-recherche-de-la-purete-originelle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/welovecinema.be\/fr\/"},{"@type":"ListItem","position":2,"name":"Les premiers, les derniers\u00a0: \u00e0 la recherche de la puret\u00e9 originelle"}]},{"@type":"WebSite","@id":"https:\/\/welovecinema.be\/nl\/#website","url":"https:\/\/welovecinema.be\/nl\/","name":"We Love Cinema","description":"Toute l\u2019information du cin\u00e9ma en Belgique","publisher":{"@id":"https:\/\/welovecinema.be\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/welovecinema.be\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/welovecinema.be\/nl\/#organization","name":"We Love Cinema","url":"https:\/\/welovecinema.be\/nl\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/welovecinema.be\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/welovecinema.be\/wp-content\/uploads\/sites\/2\/2023\/03\/Logo-We-Love-Cinema305x128.jpg","contentUrl":"https:\/\/welovecinema.be\/wp-content\/uploads\/sites\/2\/2023\/03\/Logo-We-Love-Cinema305x128.jpg","width":305,"height":128,"caption":"We Love Cinema"},"image":{"@id":"https:\/\/welovecinema.be\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/welovecinema.be","https:\/\/www.youtube.com\/channel\/UCX5LYGVhnKvYauW4Nta4HJA","https:\/\/www.instagram.com\/welovecinema.be\/"]},{"@type":"Person","@id":"https:\/\/welovecinema.be\/nl\/#\/schema\/person\/4b9b1d857f0943453a38a7c2859ef756","name":"Philippe.Pierquin","url":"https:\/\/welovecinema.be\/fr\/author\/philippe-pierquin\/"}]}},"_links":{"self":[{"href":"https:\/\/welovecinema.be\/fr\/wp-json\/wp\/v2\/posts\/82193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/welovecinema.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/welovecinema.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/welovecinema.be\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/welovecinema.be\/fr\/wp-json\/wp\/v2\/comments?post=82193"}],"version-history":[{"count":0,"href":"https:\/\/welovecinema.be\/fr\/wp-json\/wp\/v2\/posts\/82193\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/welovecinema.be\/fr\/wp-json\/wp\/v2\/media\/82204"}],"wp:attachment":[{"href":"https:\/\/welovecinema.be\/fr\/wp-json\/wp\/v2\/media?parent=82193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/welovecinema.be\/fr\/wp-json\/wp\/v2\/categories?post=82193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/welovecinema.be\/fr\/wp-json\/wp\/v2\/tags?post=82193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}